{"id":2471,"date":"2019-05-14T15:48:58","date_gmt":"2019-05-14T13:48:58","guid":{"rendered":"https:\/\/www.microsave.net\/fr\/?p=2471"},"modified":"2024-05-22T11:30:19","modified_gmt":"2024-05-22T06:00:19","slug":"credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance","status":"publish","type":"post","link":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/","title":{"rendered":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ?"},"content":{"rendered":"<h3><strong>Cr\u00e9dit digital\u00a0! Avons-nous repris les sentiers battus de la microfinance ?<\/strong><\/h3>\n<p><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40965\" src=\"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg\" alt=\"\" width=\"900\" height=\"414\" \/><\/strong><\/em><\/p>\n<p><em>\u00a0<a href=\"http:\/\/blog.microsave.net\/author\/Graham-Wright\/\">Graham Wright<\/a><u>, <\/u>aout 2017<\/em><\/p>\n<p>Je ne sais pas si je deviens cynique avec l\u2019\u00e2ge mais je suis s\u00fbr que je suis sous l\u2019effet du d\u00e9j\u00e0-vu. Nous continuons de c\u00e9l\u00e9brer l\u2019importante perc\u00e9e offerte par le cr\u00e9dit digital dans le cadre des efforts faits pour pr\u00eater aux pauvres, cependant je ne peux pas m&#8217;emp\u00eacher de le comparer \u00e0 la microfinance.\u00a0Les parall\u00e8les sautent aux yeux :<\/p>\n<ol>\n<li>On ne met pas assez l\u2019accent sur l&#8217;\u00e9pargne<\/li>\n<li>Les montants des pr\u00eats sont trop faibles pour faire une diff\u00e9rence r\u00e9elle<\/li>\n<li>On mise trop sur des comportements de remboursement<\/li>\n<li>Il y a une tendance \u00e0 l\u2019abandon<\/li>\n<li>Des emprunts multiples sont faits pour obtenir un montant utile<\/li>\n<li>Un pr\u00eat sert \u00e0 en r\u00e9gler un autre<\/li>\n<li>Il y a de plus en plus de d\u00e9fauts de paiement<\/li>\n<\/ol>\n<p>Il semble que nous devons r\u00e9apprendre, \u00e0 nos d\u00e9pens, les m\u00eames vieilles le\u00e7ons. Je me suis int\u00e9ress\u00e9 au microcr\u00e9dit (car c&#8217;est vraiment ce qu\u2019est la \u00ab\u00a0microfinance \u00bb) et je ne pouvais pas croire que le secteur <strong>n\u2019insiste que tr\u00e8s peu sur l&#8217;importance de l&#8217;\u00e9pargne.<\/strong> Pour les institutions de microcr\u00e9dit, <a href=\"http:\/\/www.microsave.net\/files\/pdf\/BN_3_Mobilising_Savings.pdf\">l\u2019\u00e9pargne \u00e9tait en g\u00e9n\u00e9ral obligatoire et servait de base non seulement pour la d\u00e9termination du montant du pr\u00eat mais \u00e9galement en tant que garantie<\/a>. Heureusement, les offres de cr\u00e9dit digital soutenues par des banques (par exemple M-Shwari, EazzyLoan ou M-Pawa), ne rendent pas l&#8217;\u00e9pargne obligatoire et inaccessible au client, mais (lorsque vous examinez la litt\u00e9rature ou la couverture m\u00e9diatique) la consid\u00e8re comme un <a href=\"http:\/\/blog.microsave.net\/two-more-revolutions-underway-in-kenya-2\/\">service secondaire<\/a> faisant partie des algorithmes qui dictent les montants des pr\u00eats. Beaucoup de clients utilisent en effet ces services d&#8217;\u00e9pargne (dont certains sont judicieusement con\u00e7us et structur\u00e9s), mais nombre d\u2019emprunteurs potentiels font des d\u00e9p\u00f4ts et des retraits dans l\u2019intention <a href=\"http:\/\/www.microsave.net\/files\/pdf\/BN_139_M_Shwari.pdf\">d\u2019exploiter le syst\u00e8me<\/a> et d\u2019augmenter le montant du pr\u00eat pour lequel ils sont \u00e9ligibles.<\/p>\n<p>\u00c0 l\u2019instar de la microfinance, les montants des pr\u00eats digitaux initiaux sont g\u00e9n\u00e9ralement trop faibles pour \u00eatre d\u2019un avantage r\u00e9el, sauf s\u2019ils servent \u00e0 arrondir les fins du mois, financer une activit\u00e9 commerciale \u00e0 tr\u00e8s court terme ou des interventions d&#8217;urgence. Ce n\u2019est pas pour dire que toutes ces raisons ne sont pas tr\u00e8s valables et importantes pour l\u2019utilisation du service; cependant <strong>la rh\u00e9torique et le battage m\u00e9diatique<\/strong> qui entourent les services de financement et leur capacit\u00e9 \u00e0 sortir les emprunteurs de la pauvret\u00e9 semblent un peu trop optimistes. C\u2019est ce qu\u2019a confirm\u00e9 l&#8217;analyse de Julie Zollman des donn\u00e9es de FinAccess 2016 (voir graphique ci-dessous) qui montre que moins de 16% de ces pr\u00eats sont utilis\u00e9s pour une activit\u00e9 \u00e9conomique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2472 size-full\" src=\"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2024\/01\/credit-digital-3-1.png\" alt=\"\" width=\"913\" height=\"488\" \/><\/p>\n<p>Cela nous am\u00e8ne \u00e0 un autre point commun. Pendant trop longtemps, le microcr\u00e9dit avait cru \u00e0 l\u2019illusion que les pr\u00eats \u00e9taient utilis\u00e9s pour des activit\u00e9s \u00e9conomiques et <strong>supposait simplement qu\u2019il avait un impact utile <\/strong>: les emprunteurs remboursaient et prenaient d\u2019autres pr\u00eats, donc l\u2019impact devait \u00eatre positif. Il semble que nous tombons dans le m\u00eame pi\u00e8ge avec notre aventure du cr\u00e9dit digital et il est peut-\u00eatre temps de proc\u00e9der \u00e0 une <a href=\"http:\/\/www.digitalcreditobservatory.org\/request-for-proposals.html\">\u00e9valuation rigoureuse<\/a> du secteur.<\/p>\n<p>L\u2019intensification graduelle de la concurrence a pouss\u00e9 les institutions de microcr\u00e9dit \u00e0 simplifier et abr\u00e9ger leurs processus d&#8217;int\u00e9gration (\u00ab formations \u00bb). Nous pouvons certainement nous attendre \u00e0 un courant similaire au niveau du cr\u00e9dit digital. Contrairement \u00e0 la simplicit\u00e9 de la proc\u00e9dure de demande de pr\u00eat de M-Shwari, EazzyLoan et d&#8217;autres syst\u00e8mes bas\u00e9s sur SMS, les longues \u00e9tapes complexes des pr\u00eateurs bas\u00e9s sur des applications <a href=\"http:\/\/blog.microsave.net\/how-smart-are-smartphone-lending-apps-in-kenya\/\">d\u00e9couragent beaucoup de gens d\u00e9sireux d\u2019adopter le produit<\/a>.<\/p>\n<p>La <a href=\"https:\/\/www.omidyar.com\/sites\/default\/files\/file_archive\/insights\/Big%20Data,%20Small%20Credit%20Report%202015\/BDSC_Digital%20Final_RV.pdf\">rh\u00e9torique autour de l&#8217;utilisation de megadonn\u00e9es<\/a> (\u00ab big data \u00bb) dans <strong>l\u2019\u00e9valuation des pr\u00eats semble \u00e9galement fallacieuse<\/strong>. Nous avons <a href=\"http:\/\/microsave.net\/resource\/where_credit_is_due_customer_experience_of_digital_credit_in_kenya\">r\u00e9cemment encadr\u00e9<\/a> des personnes \u00e0 faible revenu pour faire des demandes de pr\u00eats aupr\u00e8s de tous les grands prestataires de services de pr\u00eats au Kenya. Cela nous a permis d&#8217;\u00e9valuer le parcours client, les niveaux de divulgation des modalit\u00e9s ainsi que les montants des pr\u00eats propos\u00e9s. Cet exercice a d\u00e9montr\u00e9 qu\u2019au Kenya (peut-\u00eatre en raison de son empreinte digitale tr\u00e8s limit\u00e9e) un emprunteur pauvre peut inscrire presque n\u2019importe quel chiffre dans sa demande de pr\u00eat, il recevra un montant standard de 2 000 Ksh (20$ EU) ou 1 000 Ksh (10$ EU) selon le prestataire. \u00c0 la suite de cela, tout comme pour M-Shwari, EazzyLoan et autres syst\u00e8mes bas\u00e9s sur SMS (ainsi que pour \u00a0les institutions de microcr\u00e9dit), c&#8217;est probablement votre ant\u00e9c\u00e9dent de remboursement qui d\u00e9terminera, par-dessus tout, le montant de votre prochain pr\u00eat.<\/p>\n<p>Je suis persuad\u00e9 que l&#8217;analyse des \u00ab 1 000 points de donn\u00e9es \u00bb, des r\u00e9seaux sociaux et du comportement sera largement secondaire dans cet indicateur cl\u00e9 de solvabilit\u00e9. Cela peut, bien s\u00fbr, \u00eatre diff\u00e9rent pour les propri\u00e9taires de micro et petites entreprises qui utilisent les m\u00e9dias sociaux pour faire la promotion de leurs produits et les canaux digitaux pour effectuer des transactions. Mais pour un consommateur ordinaire \u00e0 faible revenu qui ne recharge son portable que deux fois par mois avec un peu de cr\u00e9dit et utilise peu d&#8217;applications, ses empreintes digitales sont trop insignifiantes pour vraiment peser dans la balance en sus des ant\u00e9c\u00e9dents de remboursement. Cela peut \u00e9voluer avec le temps, comme aux \u00c9tats-Unis, o\u00f9 le rapport entre la cote de cr\u00e9dit du Lending Club et la cote traditionnelle de cr\u00e9dit FICO de l&#8217;emprunteur est <a href=\"https:\/\/ideas.repec.org\/p\/fip\/fedpwp\/17-17.html\">pass\u00e9 de 80% en 2007 \u00e0 37% en 2015<\/a>. Mais il faudra alors que les personnes \u00e0 faibles revenus commencent \u00e0 participer davantage \u00e0 l&#8217;\u00e9conomie digitale.<\/p>\n<p>Lorsque je suis arriv\u00e9 pour la premi\u00e8re fois en Ouganda, l\u2019\u00e9ch\u00e9ance des pr\u00eats de toutes les IMF \u00e9taient de quatre mois et les taux d&#8217;abandon \u00e9taient de 30 \u00e0 60% par an, \u00e0 peine suffisant pour assurer la viabilit\u00e9 d&#8217;une entreprise. Des <a href=\"http:\/\/www.microsave.net\/files\/pdf\/Client_Drop_outs_From_East_African_Microfinance_Institutions.pdf\">analyses d\u00e9montraient<\/a> que <strong>beaucoup d&#8217;abandons se produisaient apr\u00e8s le premier cycle de pr\u00eat\u00a0<\/strong>: des personnes ayant essay\u00e9 un pr\u00eat de microfinance, souvent par curiosit\u00e9 ou sous la pression de leurs pairs, d\u00e9cidaient ensuite que le jeu n\u2019en valait pas la chandelle. Nous voyons exactement le m\u00eame d\u00e9fi au niveau du cr\u00e9dit digital. Notre analyse initiale des donn\u00e9es du bureau de r\u00e9f\u00e9rence de cr\u00e9dit TransUnion a montr\u00e9 que plus de la moiti\u00e9 (57% ou 1,4 million) des emprunteurs digitaux figuraient sur liste noire apr\u00e8s leur premier et unique pr\u00eat digital. Plus de 30% des nouveaux emprunteurs ayant obtenu des pr\u00eats entre juillet 2016 mars 2017 \u00e9taient d\u00e9j\u00e0 sur liste noire \u00e0 fin mars 2017.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2473 size-full\" src=\"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2024\/01\/credit-digital-4-1.png\" alt=\"\" width=\"939\" height=\"521\" \/><\/p>\n<p>Cependant, il y a une importante diff\u00e9rence \u00e0 souligner. Dans le cas du cr\u00e9dit digital, le niveau des pertes encourues sur les pr\u00eats de premier cycle est extraordinairement \u00e9lev\u00e9, en partie d\u00fb au manque de contact personnel, de garantie du groupe et \u00e0 la pression des pairs. De nombreux pr\u00eateurs digitaux se voient de ce fait dans l\u2019obligation de fixer des <a href=\"http:\/\/microsave.net\/resource\/microsave_group_managing_director_graham_a_n_wright_live_debate_from_luxembourg_digital_finance\">taux d&#8217;int\u00e9r\u00eat qui rivalisent avec ceux des pr\u00eateurs informels<\/a>. Pire, en g\u00e9n\u00e9ral, ces taux d&#8217;int\u00e9r\u00eat ne diminuent pas lorsque l&#8217;emprunteur renforce ses ant\u00e9c\u00e9dents de solvabilit\u00e9.<\/p>\n<p>En plus des abandons et des cessations de paiement \u00e0 la suite du premier cycle de pr\u00eat, les IMF ougandaises enregistraient \u00a0une croissance rapide des abandons au niveau des 5 \u00e0 7<sup>\u00e8me<\/sup> cycles de pr\u00eats. L&#8217;explication \u00e9tait simple\u00a0: de nombreux emprunteurs qui en \u00e9taient \u00e0 leur quatri\u00e8me, cinqui\u00e8me et sixi\u00e8me cycles de pr\u00eats prenaient des montants plus importants et n\u2019arrivaient pas \u00e0 trouver les sommes \u00e9lev\u00e9es n\u00e9cessaires pour faire face \u00e0 leurs remboursements hebdomadaires. Bien que notre analyse des donn\u00e9es du bureau de r\u00e9f\u00e9rence du cr\u00e9dit ne montre pas cette tendance, notre <a href=\"http:\/\/microsave.net\/resource\/microsave_group_managing_director_graham_a_n_wright_live_debate_from_luxembourg_digital_finance\">r\u00e9cente recherche au Kenya<\/a> a r\u00e9v\u00e9l\u00e9 quelques cas similaires au niveau des emprunteurs r\u00e9guliers \u00e9ligibles pour des pr\u00eats \u00e9lev\u00e9s aupr\u00e8s de pr\u00eateurs digitaux. <strong>L&#8217;obligation de rembourser une somme forfaitaire \u00e9lev\u00e9e dans un d\u00e9lai d&#8217;un mois deviendra probablement de plus en plus difficile \u00e0 mesure que le montant des pr\u00eats augmente.<\/strong> En Ouganda, les IMF ont vite appris \u00e0 prolonger la dur\u00e9e de remboursement du pr\u00eat \u00e0 6 puis 12 mois &#8211; les prestataires de cr\u00e9dit digital feront-ils de m\u00eame ?<\/p>\n<p>L&#8217;un des principaux moteurs des crises de remboursement (par exemple en Bolivie, en Inde et au Maroc) est d\u00fb au personnel des IMF encourageant la prise de pr\u00eats avec beaucoup de persuasion. Le r\u00e9sultat est que des clients qui n\u2019ont pas le d\u00e9sir (ou le besoin) d\u2019emprunter font des pr\u00eats pour des balivernes ou les remettent \u00e0 leurs amis et \u00e0 leur famille qui les utilisent. Nous observons des tendances similaires chez les prestataires de cr\u00e9dit digital qui de m\u00eame commercialisent agressivement leurs pr\u00eats (notamment par SMS). <a href=\"http:\/\/microsave.net\/resource\/microsave_group_managing_director_graham_a_n_wright_live_debate_from_luxembourg_digital_finance\">Notre recherche<\/a> a montr\u00e9 qu\u2019en cons\u00e9quence certaines personnes prennent du cr\u00e9dit digital par curiosit\u00e9 ou pour des frivolit\u00e9s tels que des divertissements de weekend (vendredi \/ samedi soir) ou des paris sportifs.<\/p>\n<p>En outre, \u00e0 l\u2019instar du microcr\u00e9dit nous assistons, au niveau du cr\u00e9dit digital, \u00e0 la mont\u00e9e de deux ph\u00e9nom\u00e8nes dangereux : 1. Les gens prennent plusieurs pr\u00eats pour r\u00e9unir le montant forfaitaire qui, selon eux, leur est n\u00e9cessaire; et 2. Ils font des pr\u00eats aupr\u00e8s des uns pour en rembourser d\u2019autres\u00a0; deux pratiques qui augmentent le risque li\u00e9 au cr\u00e9dit. Les IMF les mieux loties ont essay\u00e9 de r\u00e9soudre ces probl\u00e8mes par une meilleure compr\u00e9hension et segmentation de leurs client\u00e8les, ainsi elles octroient des pr\u00eats de micro-petites et moyennes entreprises (MPME) \u00e0 ceux qui en ont besoin et qui peuvent rembourser des montants \u00e9lev\u00e9s, tout en apportant leur appui \u00e0 ceux qui, stress\u00e9s, empruntent aupr\u00e8s des uns pour en rembourser d\u2019autres. Pour cela il est n\u00e9cessaire d\u2019avoir une interaction personnelle et (lorsqu\u2019il s\u2019agit de pr\u00eats plus importants) un changement d\u2019approche qui consiste \u00e0 rendre visite aux clients et \u00e9valuer leurs activit\u00e9s.<\/p>\n<p>Les fournisseurs de cr\u00e9dit digital doivent d\u00e9j\u00e0 commencer \u00e0 tirer des le\u00e7ons de l\u2019exp\u00e9rience des organisations de microcr\u00e9dit et \u00e0 <strong>introduire une touche personnelle dans leur processus<\/strong>, au moins lorsqu\u2019il s\u2019agit de pr\u00eats importants. \u00c0 cet effet ils peuvent impliquer des agents (contre le paiement d\u2019un compl\u00e9ment de commissions int\u00e9ressant pour initiation de pr\u00eats). L\u2019initiative de MSC en Inde a montr\u00e9 que les agents sont pr\u00eats \u00e0 assumer la responsabilit\u00e9 et \u00e0 s&#8217;impliquer dans la collecte du remboursement des pr\u00eats qu&#8217;ils ont recommand\u00e9s. Mais ils sont peu dispos\u00e9s \u00e0 mettre leur r\u00e9putation en jeu en poursuivant des personnes qu\u2019ils n\u2019ont pas recommand\u00e9es. Sans cette touche personnelle, les cr\u00e9dits digitaux demeureront les derniers \u00e9l\u00e9ments de la liste des remboursements.<\/p>\n<p>Il est clair que le cr\u00e9dit digital est un service financier important, \u00e0 fort potentiel et souvent utile pour le march\u00e9 grand public. Nous devons nous efforcer d\u2019optimiser la prestation et le recouvrement de ces pr\u00eats, aussi bien dans l\u2019int\u00e9r\u00eat des consommateurs que des prestataires. Il existe de nombreuses opportunit\u00e9s pour faciliter la modification et l&#8217;am\u00e9lioration des offres de cr\u00e9dit digital actuelles. Il va de soi que les pr\u00eateurs digitaux doivent examiner les douloureuses le\u00e7ons apprises par les institutions de microcr\u00e9dit au cours des 30 derni\u00e8res ann\u00e9es. S\u2019ils ne le font pas nous assisteront de plus en plus \u00e0 une augmentation alarmante\u00a0 de \u00ab d\u00e9linquants digitaux \u00bb et <a href=\"http:\/\/blog.microsave.net\/key-new-year-resolutions-for-the-success-of-digital-financial-services\/\">la liste noir des bureaux de cr\u00e9dit<\/a> continuera de s\u2019allonger.<\/p>\n<button class=\"simplefavorite-button\" data-postid=\"2471\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#5a5a5a;color:#ffffff;\"><i class='fa fa-bookmark-o unfavorite'><\/i><\/button>","protected":false},"excerpt":{"rendered":"<p>Je ne sais pas si je deviens cynique avec l\u2019\u00e2ge mais je suis s\u00fbr que je suis sous l\u2019effet du d\u00e9j\u00e0-vu. Nous continuons de c\u00e9l\u00e9brer l\u2019importante perc\u00e9e offerte par le cr\u00e9dit digital dans le cadre des efforts faits pour pr\u00eater aux pauvres, cependant je ne peux pas m&#8217;emp\u00eacher de le comparer \u00e0 la microfinance. Les parall\u00e8les sautent aux yeux.<\/p>\n","protected":false},"author":1031,"featured_media":40965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5451],"tags":[],"region":[5530],"class_list":["post-2471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","post_theme-banque-services-financiers-et-assurance-bfsi","post_theme-inclusion-financiere","resource_type-articles","region-afrique-de-lest"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)\" \/>\n<meta property=\"og:description\" content=\"Je ne sais pas si je deviens cynique avec l\u2019\u00e2ge mais je suis s\u00fbr que je suis sous l\u2019effet du d\u00e9j\u00e0-vu. Nous continuons de c\u00e9l\u00e9brer l\u2019importante perc\u00e9e offerte par le cr\u00e9dit digital dans le cadre des efforts faits pour pr\u00eater aux pauvres, cependant je ne peux pas m&#039;emp\u00eacher de le comparer \u00e0 la microfinance. Les parall\u00e8les sautent aux yeux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/\" \/>\n<meta property=\"og:site_name\" content=\"MicroSave Consulting (MSC)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MicroSaveConsultingFR\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-14T13:48:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T06:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rebecca Szantyr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MicroSaveFR\" \/>\n<meta name=\"twitter:site\" content=\"@MicroSaveFR\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rebecca Szantyr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/\"},\"author\":{\"name\":\"Rebecca Szantyr\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#\\\/schema\\\/person\\\/0434c54ec0112b2df6b94a87a3f4f0ba\"},\"headline\":\"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ?\",\"datePublished\":\"2019-05-14T13:48:58+00:00\",\"dateModified\":\"2024-05-22T06:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/\"},\"wordCount\":2040,\"publisher\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/133-Credit-digital-Copy-Copy-Copy.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/\",\"name\":\"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/133-Credit-digital-Copy-Copy-Copy.jpg\",\"datePublished\":\"2019-05-14T13:48:58+00:00\",\"dateModified\":\"2024-05-22T06:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/133-Credit-digital-Copy-Copy-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/133-Credit-digital-Copy-Copy-Copy.jpg\",\"width\":1280,\"height\":589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/blog\\\/2019\\\/05\\\/14\\\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/\",\"name\":\"Microsave Consulting Fr\",\"description\":\"Consulting pour Services Financiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#organization\",\"name\":\"MSC CONSULTING\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MSC.jpg\",\"contentUrl\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MSC.jpg\",\"width\":360,\"height\":340,\"caption\":\"MSC CONSULTING\"},\"image\":{\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MicroSaveConsultingFR\",\"https:\\\/\\\/x.com\\\/MicroSaveFR\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC8NseooqQHxCWDoZ63T42ig\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/#\\\/schema\\\/person\\\/0434c54ec0112b2df6b94a87a3f4f0ba\",\"name\":\"Rebecca Szantyr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g\",\"caption\":\"Rebecca Szantyr\"},\"description\":\"Rebecca Szantyr is a senior manager at MicroSave Consulting Francophone Africa.\",\"url\":\"https:\\\/\\\/www.microsave.net\\\/fr\\\/auteur\\\/rebecca-szantyr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/","og_locale":"en_US","og_type":"article","og_title":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)","og_description":"Je ne sais pas si je deviens cynique avec l\u2019\u00e2ge mais je suis s\u00fbr que je suis sous l\u2019effet du d\u00e9j\u00e0-vu. Nous continuons de c\u00e9l\u00e9brer l\u2019importante perc\u00e9e offerte par le cr\u00e9dit digital dans le cadre des efforts faits pour pr\u00eater aux pauvres, cependant je ne peux pas m'emp\u00eacher de le comparer \u00e0 la microfinance. Les parall\u00e8les sautent aux yeux.","og_url":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/","og_site_name":"MicroSave Consulting (MSC)","article_publisher":"https:\/\/www.facebook.com\/MicroSaveConsultingFR","article_published_time":"2019-05-14T13:48:58+00:00","article_modified_time":"2024-05-22T06:00:19+00:00","og_image":[{"width":1280,"height":589,"url":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg","type":"image\/jpeg"}],"author":"Rebecca Szantyr","twitter_card":"summary_large_image","twitter_creator":"@MicroSaveFR","twitter_site":"@MicroSaveFR","twitter_misc":{"Written by":"Rebecca Szantyr","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#article","isPartOf":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/"},"author":{"name":"Rebecca Szantyr","@id":"https:\/\/www.microsave.net\/fr\/#\/schema\/person\/0434c54ec0112b2df6b94a87a3f4f0ba"},"headline":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ?","datePublished":"2019-05-14T13:48:58+00:00","dateModified":"2024-05-22T06:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/"},"wordCount":2040,"publisher":{"@id":"https:\/\/www.microsave.net\/fr\/#organization"},"image":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg","articleSection":["Articles"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/","url":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/","name":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ? - MicroSave Consulting (MSC)","isPartOf":{"@id":"https:\/\/www.microsave.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#primaryimage"},"image":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg","datePublished":"2019-05-14T13:48:58+00:00","dateModified":"2024-05-22T06:00:19+00:00","breadcrumb":{"@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#primaryimage","url":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg","contentUrl":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2019\/05\/133-Credit-digital-Copy-Copy-Copy.jpg","width":1280,"height":589},{"@type":"BreadcrumbList","@id":"https:\/\/www.microsave.net\/fr\/blog\/2019\/05\/14\/credit-digital-avons-nous-repris-les-sentiers-battus-de-la-microfinance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.microsave.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9dit digital ! Avons-nous repris les sentiers battus de la microfinance ?"}]},{"@type":"WebSite","@id":"https:\/\/www.microsave.net\/fr\/#website","url":"https:\/\/www.microsave.net\/fr\/","name":"Microsave Consulting Fr","description":"Consulting pour Services Financiers","publisher":{"@id":"https:\/\/www.microsave.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.microsave.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.microsave.net\/fr\/#organization","name":"MSC CONSULTING","url":"https:\/\/www.microsave.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.microsave.net\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2022\/11\/MSC.jpg","contentUrl":"https:\/\/www.microsave.net\/fr\/wp-content\/uploads\/2022\/11\/MSC.jpg","width":360,"height":340,"caption":"MSC CONSULTING"},"image":{"@id":"https:\/\/www.microsave.net\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MicroSaveConsultingFR","https:\/\/x.com\/MicroSaveFR","https:\/\/www.youtube.com\/channel\/UC8NseooqQHxCWDoZ63T42ig"]},{"@type":"Person","@id":"https:\/\/www.microsave.net\/fr\/#\/schema\/person\/0434c54ec0112b2df6b94a87a3f4f0ba","name":"Rebecca Szantyr","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/607a29c3263e8210eeabd43b5b34afc265d522a5fe25c350322c35b05485ca68?s=96&d=mm&r=g","caption":"Rebecca Szantyr"},"description":"Rebecca Szantyr is a senior manager at MicroSave Consulting Francophone Africa.","url":"https:\/\/www.microsave.net\/fr\/auteur\/rebecca-szantyr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/posts\/2471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/users\/1031"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/comments?post=2471"}],"version-history":[{"count":4,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/posts\/2471\/revisions"}],"predecessor-version":[{"id":41906,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/posts\/2471\/revisions\/41906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/media\/40965"}],"wp:attachment":[{"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/media?parent=2471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/categories?post=2471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/tags?post=2471"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.microsave.net\/fr\/wp-json\/wp\/v2\/region?post=2471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}